{"id":8,"date":"2010-06-01T22:37:40","date_gmt":"2010-06-01T20:37:40","guid":{"rendered":"http:\/\/www.artifactconsulting.com\/lapeira\/?p=8"},"modified":"2021-04-03T12:30:56","modified_gmt":"2021-04-03T10:30:56","slug":"ladbrokes-se-la-cuela-a-elmundo-es","status":"publish","type":"post","link":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/2010\/06\/01\/ladbrokes-se-la-cuela-a-elmundo-es\/","title":{"rendered":"ladbrokes se la cuela a elmundo.es"},"content":{"rendered":"<p>El mundo.es ha estrenado recientemente su campa\u00f1a Web para el mundial de  2010 en Sud\u00e1frica. Entre los anunciantes presentes en la campa\u00f1a se  encuentra ladbrokes.com un sitio de apuestas en Internet.<\/p>\n<p>Elmundo.es se ha destacado en los \u00faltimos a\u00f1os por ser un  ejemplo a seguir en el posicionamiento internacional, sin embargo en  esta ocasi\u00f3n parece que alguien se ha equivocado al seleccionar el  formato de anuncio.<\/p>\n<p>La publicidad de ladbrokes.com en Elmundo.es para el mundial juega con  un efecto de transici\u00f3n entre una imagen bidimensional y otra  tridimensional de forma muy agresiva, con una transici\u00f3n de velocidad  irregular. El efecto logrado es como si se estuviera estampando en la  pantalla un panfleto publicitario.<\/p>\n<p>Resulta dif\u00edcil prestar atenci\u00f3n a los contenidos que se pretenden leer  una vez que la publicidad ha llamado nuestra atenci\u00f3n, es tan invasiva  que resulta dif\u00edcil centrarse en el contenido, hasta tal punto que  acabas por preferir irte de Elmundo.es. El efecto es algo parecido a lo  que ocurre en un sem\u00e1foro cuando te asaltan para limpiarte el  parabrisas: no solo no quieres ese servicio, es que adem\u00e1s la  insistencia molesta.<\/p>\n<p>Obviamente mucha gente pulsar\u00e1 en el banner para visitar la p\u00e1gina web  de ladbrokers, pero en esta epoca de empresas despiadas que les importan  un bledo los clientes y su experiencia personal no parece buena idea  ser cansino en la toma de contacto. Sobre todo cuando la competencia es  brutal: <a href=\"http:\/\/wizardofodds.com\/casinos\/\">http:\/\/wizardofodds.com\/casinos\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mundo.es ha estrenado recientemente su campa\u00f1a Web para el mundial de 2010 en Sud\u00e1frica. Entre los anunciantes presentes en la campa\u00f1a se encuentra ladbrokes.com un sitio de apuestas en Internet. Elmundo.es se ha destacado en los \u00faltimos a\u00f1os por ser un ejemplo a seguir en el posicionamiento internacional, sin embargo en esta ocasi\u00f3n parece [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[103],"tags":[94],"_links":{"self":[{"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/posts\/8"}],"collection":[{"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":6,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/posts\/8\/revisions"}],"predecessor-version":[{"id":1325,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/posts\/8\/revisions\/1325"}],"wp:attachment":[{"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/media?parent=8"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/categories?post=8"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/tags?post=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}