{"id":16,"date":"2010-05-10T22:40:56","date_gmt":"2010-05-10T20:40:56","guid":{"rendered":"http:\/\/www.artifactconsulting.com\/lapeira\/?p=16"},"modified":"2021-04-03T12:30:57","modified_gmt":"2021-04-03T10:30:57","slug":"dar-baja-en-facebook","status":"publish","type":"post","link":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/2010\/05\/10\/dar-baja-en-facebook\/","title":{"rendered":"Dar baja en Facebook"},"content":{"rendered":"<p>Facebook, la red social por excelencia es un enemigo de sus usuarios,  las cr\u00edticas relativas a privacidad y usabilidad se han encadenado desde  hace varios a\u00f1os y se cuenta por cientos los problemas que sus usuarios  han tenido con la aplicaci\u00f3n.<\/p>\n<p>Estos problemas se podr\u00edan achacar a fallos de los propios  usuarios a la hora de configurar la privacidad o usar la aplicaci\u00f3n para  publicar contenidos, pero en realidad no es culpa de los usuarios, la  aplicaci\u00f3n est\u00e1 pensada para perjudicar al usuario en beneficio de  Facebook.<\/p>\n<p>El acierto de las redes sociales ha sido exprimir a los usuarios de la  red como si se tratara de vacas orde\u00f1adas en beneficio de la empresa que  sostiene la red y en menor medida, de las empresas anunciadas en la  red.<\/p>\n<p>Podriamos enumerar 1000 motivos para dejar Facebook de forma permanente,  pero realmente ser\u00eda reescribir lo que ya se ha escrito, mi consejo  para los usuarios es, cuando hayas tenido 5 problemas con tu cuenta en  Facebook da por hecho que ocurrir\u00e1n otros 5 problemas y as\u00ed  sucesivamente hasta que dejes de usarla: cuanto antes mejor.<\/p>\n<p>\u00bfAlguien te est\u00e1 aconsejando que te metas en las redes sociales porque  \u2018son el futuro\u2019?, pues va un paso por detr\u00e1s de los hechos, otro dia  hablamos de twitter, ese foco de spam.<\/p>\n<p>Aqu\u00ed tienes un enlace interesante:<br \/>\n<a href=\"http:\/\/www.facebook.com\/group.php?gid=16929680703\">http:\/\/www.facebook.com\/group.php?gid=16929680703<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Facebook, la red social por excelencia es un enemigo de sus usuarios, las cr\u00edticas relativas a privacidad y usabilidad se han encadenado desde hace varios a\u00f1os y se cuenta por cientos los problemas que sus usuarios han tenido con la aplicaci\u00f3n. Estos problemas se podr\u00edan achacar a fallos de los propios usuarios a la hora [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[103],"tags":[94],"_links":{"self":[{"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/posts\/16"}],"collection":[{"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/comments?post=16"}],"version-history":[{"count":2,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/posts\/16\/revisions"}],"predecessor-version":[{"id":87,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/posts\/16\/revisions\/87"}],"wp:attachment":[{"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/media?parent=16"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/categories?post=16"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/tags?post=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}