{"id":1232,"date":"2014-05-02T22:04:51","date_gmt":"2014-05-02T20:04:51","guid":{"rendered":"http:\/\/www.artifactconsulting.com\/lapeira\/?p=1232"},"modified":"2021-04-03T12:11:04","modified_gmt":"2021-04-03T10:11:04","slug":"opinion-experta-de-amazon-web-services","status":"publish","type":"post","link":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/2014\/05\/02\/opinion-experta-de-amazon-web-services\/","title":{"rendered":"Mi opini\u00f3n de Amazon Web Services"},"content":{"rendered":"<p>Ning\u00fan administrador crack de los que conozco me hab\u00eda hablado ni bien ni mal de AWS, sencillamente nunca lo hab\u00edan probado, como era tambi\u00e9n mi caso hasta hace unos meses. Sin embargo un amigo no administrador me coment\u00f3 que eso era el futuro, la revoluci\u00f3n, que hospedar en tus propios servidores era el pasado y yo, conociendo su capacidad t\u00e9cnica, le hice caso y lo prob\u00e9.<\/p>\n<p>Tambi\u00e9n me puse a indagar y en general estos son los argumentos m\u00e1s comentados sobre los pros y los contras de AWS (ordenados por la frecuencia con la que se suelen mencionar).<\/p>\n<p>&#8211; <span style=\"color: #008000;\">A favor<\/span>: &#8220;Te ahorras el SAU, las conexiones dobles, los routers, tirar cable y deslomarte f\u00edsicamente&#8221;.<\/p>\n<p>&#8211; <span style=\"color: #ff9900;\">En contra<\/span>: &#8220;No puedo quitar el cable de la parte trasera de la maquina&#8221;.<\/p>\n<p>&#8211; <span style=\"color: #008000;\">A favor<\/span>: &#8220;Imag\u00ednate que tu proyecto se pone de moda y en minutos despega, te ponen m\u00e1s nodos bajo demanda&#8221; (no es as\u00ed de f\u00e1cil y hay varios posts en Internet de gente que ya ha sufrido las limitaciones t\u00e9cnicas de la implementaci\u00f3n facilitada por AWS para esto).<\/p>\n<p>&#8211; <span style=\"color: #ff9900;\">En contra<\/span>: &#8220;Te enteras del coste a toro pasado?!&#8221; (en la pr\u00e1ctica s\u00ed, acaban de montar un &#8220;estimador&#8221; en Abril de 2014 cuando llevan funcionando a\u00f1os pero el estimador se basa en datos hist\u00f3ricos de tus costes).<\/p>\n<p>&#8211;\u00a0<span style=\"color: #008000;\">A favor<\/span>: &#8220;Routing, balanceo, caches,&#8230; todo te lo da empezado, si no tienes ni idea es genial&#8221;<\/p>\n<p>&#8211; <span style=\"color: #ff9900;\">En contra<\/span>: &#8220;Las opciones de configuraci\u00f3n visual pretenden dar la impresi\u00f3n de que es facilisimo tener una granja de servidores funcionando, pero la mayor\u00eda se sigue haciendo como siempre&#8221;.<\/p>\n<p>&#8211;\u00a0<span style=\"color: #008000;\">A favor<\/span>: &#8220;Tiene mecanismos de seguridad por defecto que hubiera apreciado cuando empec\u00e9 a hospedar proyectos&#8221;.<\/p>\n<p>&#8211; <span style=\"color: #ff9900;\">En contra<\/span>: &#8220;No me deja hacer todo lo que hago en mis propios servidores y la consola web me parece para ni\u00f1os&#8221;<\/p>\n<p>Mi opini\u00f3n personal es que me revienta que me cobren por consumo, cuando lo caro de todo esto es el know-how y las horas de configuraci\u00f3n y administraci\u00f3n. Que te cobren por CPU, ancho de banda, memoria y disco es mucho m\u00e1s caro que montarte un par de clusters distribuidos geogr\u00e1ficamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ning\u00fan administrador crack de los que conozco me hab\u00eda hablado ni bien ni mal de AWS, sencillamente nunca lo hab\u00edan probado, como era tambi\u00e9n mi caso hasta hace unos meses. Sin embargo un amigo no administrador me coment\u00f3 que eso era el futuro, la revoluci\u00f3n, que hospedar en tus propios servidores era el pasado y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[103],"tags":[94],"_links":{"self":[{"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/posts\/1232"}],"collection":[{"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/comments?post=1232"}],"version-history":[{"count":5,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/posts\/1232\/revisions"}],"predecessor-version":[{"id":1831,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/posts\/1232\/revisions\/1831"}],"wp:attachment":[{"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/media?parent=1232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/categories?post=1232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.artifactconsulting.com\/lapeira\/index.php\/wp-json\/wp\/v2\/tags?post=1232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}